{"id":2538,"date":"2017-11-16T15:43:03","date_gmt":"2017-11-16T17:43:03","guid":{"rendered":"http:\/\/extinil.com.br\/?p=2538"},"modified":"2017-11-16T15:43:03","modified_gmt":"2017-11-16T17:43:03","slug":"policia-conclui-identificacao-dos-71-mortos-no-incendio-da-grenfell-tower","status":"publish","type":"post","link":"https:\/\/extinil.com.br\/index.php\/2017\/11\/16\/policia-conclui-identificacao-dos-71-mortos-no-incendio-da-grenfell-tower\/","title":{"rendered":"Pol\u00edcia conclui identifica\u00e7\u00e3o dos 71 mortos no inc\u00eandio da Grenfell Tower"},"content":{"rendered":"<p>LONDRES \u2014 Ficou em 71 o n\u00famero final de mortos em decorr\u00eancia do inc\u00eandio que destruiu a Grenfell Tower em Londres no \u00faltimo 14 de junho, informou a Pol\u00edcia Metropolitana, nesta quinta-feira, cinco meses ap\u00f3s meticulosas opera\u00e7\u00f5es de busca e recupera\u00e7\u00e3o. Os oficiais agora acreditam que todas as v\u00edtimas fatais foram recuperadas e identificadas. A investiga\u00e7\u00e3o envolveu a separa\u00e7\u00e3o de toneladas de detritos \u00e0 m\u00e3o para identificar todos os restos humanos no edif\u00edcio carbonizado.<\/p>\n<p>O n\u00famero estava em 80, mas caiu depois que ficou constatado que algumas pessoas foram contabilizadas como desaparecidas mais de uma vez, outras que moravam na torre, e estavam na lista de prov\u00e1veis v\u00edtimas, n\u00e3o estavam em casa na noite do inc\u00eandio, e ainda houve quem relatasse falsas v\u00edtimas em fraudes que visavam compensa\u00e7\u00e3o financeira.<\/p>\n<p>A taxa final inclui adultos e crian\u00e7as que morreram na torre durante o inc\u00eandio, al\u00e9m de um beb\u00ea que morreu logo ap\u00f3s sua m\u00e3e, ainda gr\u00e1vida, ter escapado do 21\u00ba andar, quando sofreu uma intensa inala\u00e7\u00e3o de fuma\u00e7a enquanto descia. A m\u00e3e sobreviveu.<\/p>\n<p>\u2014 Equipes especializadas que trabalharam dentro da Grenfell Tower e no necrot\u00e9rio ultrapassaram os limites do que era cientificamente poss\u00edvel para identificar as pessoas \u2014, disse o comandante da Pol\u00edcia Metropolitana Stuart Cundy, respons\u00e1vel pelas opera\u00e7\u00f5es no pr\u00e9dio.<\/p>\n<p>&nbsp;<\/p>\n<p>Cundy afirmou que quando ele entrou pela primeira vez na Torre Grenfell ap\u00f3s o inc\u00eandio, a devasta\u00e7\u00e3o era tal que ele temia que n\u00e3o fosse poss\u00edvel encontrar, recuperar e identificar todos aqueles que morreram.<\/p>\n<p>Os policiais, assistidos por antrop\u00f3logos forenses, arque\u00f3logos e especialistas em uso de ci\u00eancias dent\u00e1rias para identificar restos humanos desconhecidos, procuraram cada apartamento em cada andar e em toda \u00e1rea comunit\u00e1ria.<\/p>\n<p>\u2014 Eu sei que todos e cada um dos membros da equipe fizeram tudo o que puderam para tornar isso poss\u00edvel. Eles fizeram isso para todas as pessoas que perderam a vida, suas fam\u00edlias e entes queridos, e todos aqueles que consideravam a Grenfell Tower seu lar \u2014 frisou.<\/p>\n<p>A Grenfell Tower abrigava uma comunidade multi-\u00e9tnica numa propriedade localizada no rico bairro de Kensington e Chelsea, onde vive um grande n\u00famero de milion\u00e1rios. A trag\u00e9dia provocou o debate pol\u00edtico sobre as estritas desigualdades sociais de Londres e se a neglig\u00eancia das habita\u00e7\u00f5es sociais desempenharam um papel na causa do inc\u00eandio. Est\u00e1 em andamento uma investiga\u00e7\u00e3o criminal que pode resultar em multas individuais ou organizacionais. Um inqu\u00e9rito p\u00fablico separado visa averiguar quaisquer falhas ou irregularidades na concep\u00e7\u00e3o, constru\u00e7\u00e3o ou manuten\u00e7\u00e3o da torre.<\/p>\n<p>O fogo na Grenfell Tower come\u00e7ou devido a um curto-circuito em uma geladeira e se alastrou rapidamente pelo edif\u00edcio pelo teor inflam\u00e1vel do revestimento instalado em julho de 2016 na parte externa do pr\u00e9dio. O agente a cargo da investiga\u00e7\u00e3o disse que o material exterior do pr\u00e9dio foi reprovado em todos os testes de seguran\u00e7a de inc\u00eandio.<\/p>\n<div id=\"pub-retangulo-3\" class=\"arroba publicidade clearfix\" data-google-query-id=\"CInd1Y_Rw9cCFRWCkQodoaEH8w\"><\/div>\n<p>Mais de 90 pr\u00e9dios com revestimentos semelhantes \u00e0 Grenfell Tower em toda a Inglaterra tamb\u00e9m foram reprovados em testes de seguran\u00e7a. A empresa norte-americana Arconic informou que interrompeu\u00a0as vendas globais de seu revestimento Reynobond PE, que foi usado na Grenfell Tower, para uso em arranha-c\u00e9us ap\u00f3s o inc\u00eandio.<\/p>\n<p>Fonte: O Globo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LONDRES \u2014 Ficou em 71 o n\u00famero final de mortos em decorr\u00eancia do inc\u00eandio que destruiu a Grenfell Tower em Londres no \u00faltimo 14 de junho, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2540,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/extinil.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2538"}],"collection":[{"href":"https:\/\/extinil.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/extinil.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/extinil.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/extinil.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2538"}],"version-history":[{"count":1,"href":"https:\/\/extinil.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2538\/revisions"}],"predecessor-version":[{"id":2541,"href":"https:\/\/extinil.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2538\/revisions\/2541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/extinil.com.br\/index.php\/wp-json\/wp\/v2\/media\/2540"}],"wp:attachment":[{"href":"https:\/\/extinil.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/extinil.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/extinil.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}